{"id":5361,"date":"2025-06-21T06:06:44","date_gmt":"2025-06-21T06:06:44","guid":{"rendered":"https:\/\/info-eforie.ro\/index.php\/2025\/06\/21\/chelsea-0-acum-digi-sport-1-goool-londonezii-lupta-pentru-champions-league\/"},"modified":"2025-06-21T06:06:44","modified_gmt":"2025-06-21T06:06:44","slug":"chelsea-0-acum-digi-sport-1-goool-londonezii-lupta-pentru-champions-league","status":"publish","type":"post","link":"https:\/\/info-eforie.ro\/index.php\/2025\/06\/21\/chelsea-0-acum-digi-sport-1-goool-londonezii-lupta-pentru-champions-league\/","title":{"rendered":"Chelsea -0, ACUM, Digi Sport 1. GOOOL! Londonezii lupt\u0103 pentru Champions League"},"content":{"rendered":"<p>Chelsea &#8211; Everton 1-0, ACUM, Digi Sport 1. GOOOL! Londonezii lupt\u0103 pentru Champions League&#8230;<br \/><a href=\"https:\/\/www.digisport.ro\/fotbal\/premier-league\/chelsea-everton-0-0-acum-digi-sport-1-londonezii-lupta-pentru-champions-league-3556533\" class=\"button purchase\" rel=\"nofollow noopener\" target=\"_blank\">Read More<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chelsea &#8211; Everton 1-0, ACUM, Digi Sport 1. GOOOL! Londonezii lupt\u0103 pentru Champions League&#8230;Read More<\/p>\n","protected":false},"author":1,"featured_media":5362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/info-eforie.ro\/index.php\/wp-json\/wp\/v2\/posts\/5361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/info-eforie.ro\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/info-eforie.ro\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/info-eforie.ro\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/info-eforie.ro\/index.php\/wp-json\/wp\/v2\/comments?post=5361"}],"version-history":[{"count":0,"href":"https:\/\/info-eforie.ro\/index.php\/wp-json\/wp\/v2\/posts\/5361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/info-eforie.ro\/index.php\/wp-json\/wp\/v2\/media\/5362"}],"wp:attachment":[{"href":"https:\/\/info-eforie.ro\/index.php\/wp-json\/wp\/v2\/media?parent=5361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/info-eforie.ro\/index.php\/wp-json\/wp\/v2\/categories?post=5361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/info-eforie.ro\/index.php\/wp-json\/wp\/v2\/tags?post=5361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}